{"id":415,"date":"2016-08-16T00:01:55","date_gmt":"2016-08-16T00:01:55","guid":{"rendered":"http:\/\/localhost\/google\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg"},"modified":"2016-08-16T00:01:55","modified_gmt":"2016-08-16T00:01:55","slug":"solenoid-coil","status":"inherit","type":"attachment","link":"https:\/\/printechnepal.com\/index.php\/solenoid-coils\/solenoid-coil\/#main","title":{"rendered":"Solenoid Coil"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-415","attachment","type-attachment","status-inherit","hentry","post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solenoid Coil - PRINTECHNEPAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solenoid Coil - PRINTECHNEPAL\" \/>\n<meta property=\"og:url\" content=\"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg\" \/>\n<meta property=\"og:site_name\" content=\"PRINTECHNEPAL\" \/>\n<meta property=\"og:image\" content=\"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"497\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/printechnepal.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Solenoid-Coil.jpg\",\"url\":\"http:\\\/\\\/printechnepal.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Solenoid-Coil.jpg\",\"name\":\"Solenoid Coil - PRINTECHNEPAL\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/printechnepal.com\\\/#website\"},\"datePublished\":\"2016-08-16T00:01:55+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/printechnepal.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Solenoid-Coil.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/printechnepal.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Solenoid-Coil.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/printechnepal.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Solenoid-Coil.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/printechnepal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solenoid Coils\",\"item\":\"http:\\\/\\\/printechnepal.com\\\/index.php\\\/solenoid-coils\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Solenoid Coil\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/printechnepal.com\\\/#website\",\"url\":\"http:\\\/\\\/printechnepal.com\\\/\",\"name\":\"PRINTECHNEPAL\",\"description\":\"An Official Website Of PRINTECHNEPAL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/printechnepal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solenoid Coil - PRINTECHNEPAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg","og_locale":"en_US","og_type":"article","og_title":"Solenoid Coil - PRINTECHNEPAL","og_url":"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg","og_site_name":"PRINTECHNEPAL","og_image":[{"width":497,"height":531,"url":"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg","url":"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg","name":"Solenoid Coil - PRINTECHNEPAL","isPartOf":{"@id":"http:\/\/printechnepal.com\/#website"},"datePublished":"2016-08-16T00:01:55+00:00","breadcrumb":{"@id":"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/printechnepal.com\/"},{"@type":"ListItem","position":2,"name":"Solenoid Coils","item":"http:\/\/printechnepal.com\/index.php\/solenoid-coils\/"},{"@type":"ListItem","position":3,"name":"Solenoid Coil"}]},{"@type":"WebSite","@id":"http:\/\/printechnepal.com\/#website","url":"http:\/\/printechnepal.com\/","name":"PRINTECHNEPAL","description":"An Official Website Of PRINTECHNEPAL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/printechnepal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"281\" height=\"300\" src=\"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-281x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-281x300.jpg 281w, https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg 497w\" sizes=\"auto, (max-width: 281px) 100vw, 281px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":497,"height":531,"file":"2016\/08\/Solenoid-Coil.jpg","sizes":{"woocommerce_thumbnail":{"file":"Solenoid-Coil-300x300.jpg","width":300,"height":300,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"Solenoid-Coil-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-100x100.jpg"},"thumbnail":{"file":"Solenoid-Coil-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-150x150.jpg"},"medium":{"file":"Solenoid-Coil-281x300.jpg","width":281,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-281x300.jpg"},"post-thumbnail":{"file":"Solenoid-Coil-497x380.jpg","width":497,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-497x380.jpg"},"vantage-thumbnail-no-sidebar":{"file":"Solenoid-Coil-497x380.jpg","width":497,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-497x380.jpg"},"vantage-slide":{"file":"Solenoid-Coil-497x480.jpg","width":497,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-497x480.jpg"},"vantage-carousel":{"file":"Solenoid-Coil-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-272x182.jpg"},"vantage-grid-loop":{"file":"Solenoid-Coil-436x272.jpg","width":436,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-436x272.jpg"},"sow-carousel-default":{"file":"Solenoid-Coil-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil-272x182.jpg"},"full":{"file":"Solenoid-Coil.jpg","width":497,"height":531,"mime_type":"image\/jpeg","source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":411,"source_url":"https:\/\/printechnepal.com\/wp-content\/uploads\/2016\/08\/Solenoid-Coil.jpg","filename":"Solenoid-Coil.jpg","filesize":65748,"_links":{"self":[{"href":"https:\/\/printechnepal.com\/index.php\/wp-json\/wp\/v2\/media\/415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/printechnepal.com\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/printechnepal.com\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/printechnepal.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/printechnepal.com\/index.php\/wp-json\/wp\/v2\/comments?post=415"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":411,"href":"https:\/\/printechnepal.com\/index.php\/wp-json\/wp\/v2\/pages\/411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}